{"id":515,"date":"2022-04-17T15:21:37","date_gmt":"2022-04-17T13:21:37","guid":{"rendered":"https:\/\/erasmusxxi.eu\/?p=515"},"modified":"2022-08-17T11:20:45","modified_gmt":"2022-08-17T09:20:45","slug":"gymnasium-erasmianum","status":"publish","type":"post","link":"https:\/\/erasmusxxi.eu\/index.php\/fr\/2022\/04\/17\/gymnasium-erasmianum\/","title":{"rendered":"Gymnasium Erasmianum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vendredi matin, le 15 avril, j&#8217;\u00e9tais de retour dans mon ancienne \u00e9cole \u00e0 Rotterdam. L\u00e0-bas, j&#8217;ai pu apprendre quelque chose \u00e0 l&#8217;\u00e2ge de 16 ans et je le fais encore \u00e0 66 ans. Dans sa <a rel=\"noreferrer noopener\" href=\"https:\/\/www.erasmiaans.nl\/de-school\/visie\/\" target=\"_blank\">Visie \u2013 Erasmiaans Gymnasium<\/a> l&#8217;\u00e9cole d\u00e9clare, dans la lign\u00e9e d&#8217;Erasmus, qu&#8217;elle veut faire plus qu&#8217;\u00e9duquer pour obtenir un dipl\u00f4me, mais \u00e9duquer des personnes enti\u00e8res. Comment font-ils cela et qu&#8217;en r\u00e9sulte-t-il ? Je m&#8217;entretiens avec le recteur Bouwien Bovenberg et aussi avec deux classes dans les cours de mentorat de deux autres anciens Erasmusiens : Joris Dane (4A) et Christo Hulst (5D).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les \u00e9l\u00e8ves du Gymnasium Erasmianum dans leur premi\u00e8re ann\u00e9e rendent dans leur ancienne \u00e9cole primaire pour raconter quelque chose sur le lyc\u00e9e et son homonyme. Tout ne semble pas \u00eatre rest\u00e9 dans leur m\u00e9moire apr\u00e8s quelques ann\u00e9es, mais ils avaient tous quelque chose en t\u00eate et souhaitaient en savoir plus sur \u00c9rasme. En ce qui me concerne, je dirais que c&#8217;\u00e9tait moins le cas lorsque j&#8217;\u00e9tais \u00e0 l&#8217;\u00e9cole. Quelques remarques dignes d&#8217;int\u00e9r\u00eat :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Il est amusant que Rotterdam donne le nom d&#8217;\u00c9rasme \u00e0 un lyc\u00e9e, une universit\u00e9 et un pont. Quel est le lien entre \u00c9rasme et Rotterdam ? <\/li><li>Je ne savais pas que tant d&#8217;\u00e9coles en Europe portaient le nom d&#8217;\u00c9rasme. Pourquoi donner son nom \u00e0 une \u00e9cole ? <\/li><li>Il \u00e9tait meilleur en latin que moi. <\/li><li>Il a toujours recherch\u00e9 la paix, mais au cours de sa vie, quelque chose s&#8217;est produit qui a entra\u00een\u00e9 de nombreux conflits. &#8220;Ah oui, la R\u00e9volution fran\u00e7aise.&#8221; ?!<\/li><li>Si les gens qui avaient ses id\u00e9es risquaient d&#8217;\u00eatre br\u00fbl\u00e9s, comment est-il mort ?<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Merci de m&#8217;avoir permis de vous rendre visite pendant cette p\u00e9riode toujours tr\u00e8s charg\u00e9e pour les \u00e9coles. Le dernier jour de classe de la sixi\u00e8me ann\u00e9e a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 par une cascade d&#8217;examens pendant que je me promenais. Et apr\u00e8s Corona, les \u00e9coles ont assez de choses \u00e0 faire en plus de toute fa\u00e7on. C&#8217;est bien qu&#8217;il y ait eu aussi du temps pour m&#8217;apprendre.<\/p>\n\n\n\n<p class=\"has-larger-font-size wp-block-paragraph\">L&#8217;esprit d&#8217;\u00c9rasme en action<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la salle du personnel, j&#8217;ai \u00e9galement entendu dire que les enseignants d&#8217;Erasmus agissent et se r\u00e9f\u00e8rent \u00e0 l&#8217;esprit d&#8217;Erasmus dans leurs cours et leurs r\u00e9unions. Il n&#8217;est souvent pas facile de le rendre concret, par exemple son aversion pour l&#8217;hypocrisie. J&#8217;ai eu la chance d&#8217;assister \u00e0 la fin d&#8217;un cours sur la violence polici\u00e8re excessive aux \u00c9tats-Unis. Cela a donn\u00e9 lieu \u00e0 une discussion avec la classe :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Que penserait \u00c9rasme d&#8217;une action aussi violente ? <\/li><li>Il la d\u00e9sapprouverait certainement. <\/li><li>Mais la police n&#8217;a-t-elle pas le droit d&#8217;utiliser la force pour une raison pr\u00e9cise ? <\/li><li>En effet, elle l&#8217;a, mais ce droit lui a \u00e9t\u00e9 accord\u00e9 pour pouvoir prot\u00e9ger les gens. <\/li><li>\u00c9rasme a \u00e9galement toujours pens\u00e9 qu&#8217;il ne fallait pas appliquer les r\u00e8gles parce qu&#8217;elles existent, mais pour atteindre un meilleur objectif.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"419\" height=\"420\" src=\"https:\/\/erasmusxxi.eu\/wp-content\/uploads\/2022\/05\/voor-EG-Rdam.jpg\" alt=\"\" class=\"wp-image-362\" srcset=\"https:\/\/erasmusxxi.eu\/wp-content\/uploads\/2022\/05\/voor-EG-Rdam.jpg 419w, https:\/\/erasmusxxi.eu\/wp-content\/uploads\/2022\/05\/voor-EG-Rdam-300x300.jpg 300w, https:\/\/erasmusxxi.eu\/wp-content\/uploads\/2022\/05\/voor-EG-Rdam-150x150.jpg 150w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vendredi matin, le 15 avril, j&#8217;\u00e9tais de retour dans mon ancienne \u00e9cole \u00e0 Rotterdam. L\u00e0-bas, j&#8217;ai pu apprendre quelque chose \u00e0 l&#8217;\u00e2ge de 16 ans et je le fais encore \u00e0 66 ans. Dans sa Visie \u2013 Erasmiaans Gymnasium l&#8217;\u00e9cole d\u00e9clare, dans la lign\u00e9e d&#8217;Erasmus, qu&#8217;elle veut faire plus qu&#8217;\u00e9duquer pour obtenir un dipl\u00f4me, mais&hellip; <\/p>\n<div class=\"readmore-wrapper\"><a href=\"https:\/\/erasmusxxi.eu\/index.php\/fr\/2022\/04\/17\/gymnasium-erasmianum\/\" class=\"more-link\">Lees <\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-515","post","type-post","status-publish","format-standard","hentry","category-zonder-categorie-fr"],"_links":{"self":[{"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/posts\/515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/comments?post=515"}],"version-history":[{"count":2,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/posts\/515\/revisions"}],"predecessor-version":[{"id":518,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/posts\/515\/revisions\/518"}],"wp:attachment":[{"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/media?parent=515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/categories?post=515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erasmusxxi.eu\/index.php\/wp-json\/wp\/v2\/tags?post=515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}